{"id":34740,"date":"2026-03-30T09:17:05","date_gmt":"2026-03-30T12:17:05","guid":{"rendered":"https:\/\/institutosantosdumont.org.br\/?p=34740"},"modified":"2026-03-30T13:26:42","modified_gmt":"2026-03-30T16:26:42","slug":"projeto-terapeutico-singular-sera-tema-central-do-sig-rehabilitar-em-2026","status":"publish","type":"post","link":"https:\/\/institutosantosdumont.org.br\/es\/projeto-terapeutico-singular-sera-tema-central-do-sig-rehabilitar-em-2026\/","title":{"rendered":"El Proyecto Terap\u00e9utico Individual ser\u00e1 el tema central del SIG Re(h)abilitar en 2026.\u00a0"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Los pilares que sustentan la implementaci\u00f3n del Proyecto Terap\u00e9utico Individual (PTI) en el contexto de la rehabilitaci\u00f3n de personas con discapacidad guiar\u00e1n los debates del Grupo de Inter\u00e9s Especial Re(h)abilitar en 2026. La videoconferencia, coordinada por el Instituto Santos Dumont (ISD) y la UFRN, se celebra mensualmente, y la primera reuni\u00f3n est\u00e1 prevista para el pr\u00f3ximo mi\u00e9rcoles 1 de abril.<\/span><\/p>\n<p>El proyecto organiza sesiones colaborativas en las que investigadores y profesionales de la salud se re\u00fanen virtualmente para debatir temas relacionados con la docencia, la investigaci\u00f3n, la atenci\u00f3n sanitaria, la gesti\u00f3n y la evaluaci\u00f3n remota. El acceso a la videoconferencia es gratuito a trav\u00e9s de [link\/platform name]. <a href=\"https:\/\/rcc.rnp.br\/RUTE\/aovivo\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Red Universitaria de Telemedicina (RUTE)<\/a>, mediante registro previo en la plataforma.<\/p>\n<p><span style=\"font-weight: 400;\">La sesi\u00f3n inaugural estar\u00e1 a cargo del Coordinador General de Salud para Personas con Discapacidad del Ministerio de Salud, Arthur Medeiros, y la coordinadora del Centro de Rehabilitaci\u00f3n Especializada del ISD, Camila Sim\u00e3o. Los profesionales debatir\u00e1n sobre el tema &quot;El PTS como herramienta para la gesti\u00f3n y coordinaci\u00f3n de la atenci\u00f3n en la Red de Atenci\u00f3n a Personas con Discapacidad (RCPD)&quot;.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para Camila Sim\u00e3o, centrarse en el s\u00edndrome postraum\u00e1tico es necesario e importante para fortalecer el RCPD en la gesti\u00f3n y coordinaci\u00f3n de la atenci\u00f3n.<\/span> <span style=\"font-weight: 400;\">\u201cEste tema busca fomentar la generaci\u00f3n de conocimiento y el intercambio de experiencias para responder a una demanda del RCPD, que necesita abordar este tema para su implementaci\u00f3n efectiva. A lo largo de las nueve reuniones que se llevar\u00e1n a cabo hasta fin de a\u00f1o, discutiremos los pilares necesarios para esta implementaci\u00f3n, as\u00ed como consejos e intercambios de experiencias exitosas\u201d, afirm\u00f3.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El Proyecto Terap\u00e9utico Individual (PTI) es un conjunto de acciones interdisciplinarias dise\u00f1adas para una persona y su familia, centradas en las necesidades del contexto de salud. Busca superar el modelo biom\u00e9dico tradicional, priorizando la autonom\u00eda del usuario y el v\u00ednculo con el equipo. El proceso incluye diagn\u00f3stico, definici\u00f3n de objetivos, divisi\u00f3n de responsabilidades y reevaluaci\u00f3n continua.<\/span><\/p>\n<p><b>Acerca de Re(h)habilitate GIS<\/b><\/p>\n<p><span style=\"font-weight: 400;\">El SIG Re(h)abilitar es un Grupo de Inter\u00e9s Especial de la Red Universitaria de Telemedicina (RUTE), una iniciativa del Ministerio de Ciencia, Tecnolog\u00eda e Innovaci\u00f3n (MCTI), con el apoyo de Finep y Abrahue, y coordinada por la Red Nacional de Educaci\u00f3n e Investigaci\u00f3n (RNP). El proyecto integra a investigadores y profesionales de la educaci\u00f3n, el trabajo interprofesional y la investigaci\u00f3n en las \u00e1reas de habilitaci\u00f3n y rehabilitaci\u00f3n de personas con discapacidad.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Desde 2018, el grupo ha abordado diferentes temas anuales. En 2026, las actividades se realizar\u00e1n en colaboraci\u00f3n con la Coordinaci\u00f3n de Atenci\u00f3n Especializada en Salud de Personas con Discapacidad del Ministerio de Salud. Las reuniones son s\u00edncronas, por videoconferencia, con acceso gratuito para profesionales y estudiantes de todo Brasil.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Las sesiones se realizan siempre el primer mi\u00e9rcoles de cada mes, de 13:30 a 15:00. Para participar, los nuevos usuarios deben registrarse en la plataforma RNP a trav\u00e9s del sitio web. <\/span><a href=\"https:\/\/rcc.rnp.br\/RUTE\/aovivo\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"><span style=\"font-weight: 400;\">https:\/\/rcc.rnp.br\/RUTE\/aovivo<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><b>Servicio:<\/b><\/p>\n<p><b>SIG Re(h)habilitate 2026<\/b><\/p>\n<p><b>Evento:<\/b><span style=\"font-weight: 400;\"> SIG Re(h)habilitate 2026<\/span><\/p>\n<p><b>Tema:<\/b><span style=\"font-weight: 400;\"> El Proyecto Terap\u00e9utico Individual (PTI) como herramienta para la gesti\u00f3n y coordinaci\u00f3n de la atenci\u00f3n.<\/span><\/p>\n<p><b>Conferencia inaugural:<\/b><span style=\"font-weight: 400;\"> 1 de abril de 2026<\/span><\/p>\n<p><b>Tiempo:<\/b><span style=\"font-weight: 400;\"> 13:30 a 15:00<\/span><\/p>\n<p><b>Registro y acceso a la plataforma:<\/b><a href=\"https:\/\/rcc.rnp.br\/RUTE\/aovivo\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"> <span style=\"font-weight: 400;\">https:\/\/rcc.rnp.br\/RUTE\/aovivo<\/span><\/a><\/p>\n<p><b>Acerca del distrito escolar independiente<\/b><\/p>\n<p><span style=\"font-weight: 400;\">El Instituto Santos Dumont (ISD) es una Organizaci\u00f3n Social del Poder Ejecutivo Federal, supervisada por el Ministerio de Educaci\u00f3n, con la intervenci\u00f3n del Ministerio de Deportes. Abarca el Instituto Internacional de Neurociencias Edmond y Lily Safra y el Centro de Educaci\u00f3n e Investigaci\u00f3n en Salud Anita Garibaldi, ambos ubicados en Maca\u00edba. La misi\u00f3n del ISD es promover la educaci\u00f3n para la vida, formando ciudadanos mediante actividades integradas de docencia, investigaci\u00f3n y extensi\u00f3n, adem\u00e1s de contribuir a una transformaci\u00f3n m\u00e1s justa y humana de la realidad social brasile\u00f1a.<\/span><\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Los pilares que conforman la implementaci\u00f3n del Proyecto Terap\u00e9utico Individual (PTI) en el contexto de la rehabilitaci\u00f3n de personas con discapacidad guiar\u00e1n las discusiones del Grupo de Inter\u00e9s Especial Re(h)abilitar en 2026. La videoconferencia, coordinada por el Instituto Santos Dumont (ISD) y la UFRN, se realiza mensualmente, y la primera reuni\u00f3n est\u00e1 programada para el pr\u00f3ximo mi\u00e9rcoles 1 de abril. [\u2026]<\/p>","protected":false},"author":10,"featured_media":34741,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[7,1,8,11,271],"tags":[],"class_list":["post-34740","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ceps","category-destaque_noticia","category-ensino","category-extensao","category-reabilitacao"],"acf":[],"_links":{"self":[{"href":"https:\/\/institutosantosdumont.org.br\/es\/wp-json\/wp\/v2\/posts\/34740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/institutosantosdumont.org.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/institutosantosdumont.org.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/institutosantosdumont.org.br\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/institutosantosdumont.org.br\/es\/wp-json\/wp\/v2\/comments?post=34740"}],"version-history":[{"count":3,"href":"https:\/\/institutosantosdumont.org.br\/es\/wp-json\/wp\/v2\/posts\/34740\/revisions"}],"predecessor-version":[{"id":34744,"href":"https:\/\/institutosantosdumont.org.br\/es\/wp-json\/wp\/v2\/posts\/34740\/revisions\/34744"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/institutosantosdumont.org.br\/es\/wp-json\/wp\/v2\/media\/34741"}],"wp:attachment":[{"href":"https:\/\/institutosantosdumont.org.br\/es\/wp-json\/wp\/v2\/media?parent=34740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/institutosantosdumont.org.br\/es\/wp-json\/wp\/v2\/categories?post=34740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/institutosantosdumont.org.br\/es\/wp-json\/wp\/v2\/tags?post=34740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}