{"id":35562,"date":"2026-07-15T15:21:39","date_gmt":"2026-07-15T18:21:39","guid":{"rendered":"https:\/\/institutosantosdumont.org.br\/?p=35562"},"modified":"2026-07-15T15:22:24","modified_gmt":"2026-07-15T18:22:24","slug":"pesquisa-do-isd-apresentada-em-evento-internacional-relata-sobre-uso-de-interface-cerebro-computador-para-treinamento-cognitivo-em-pessoas-com-covid-longa","status":"publish","type":"post","link":"https:\/\/institutosantosdumont.org.br\/es\/pesquisa-do-isd-apresentada-em-evento-internacional-relata-sobre-uso-de-interface-cerebro-computador-para-treinamento-cognitivo-em-pessoas-com-covid-longa\/","title":{"rendered":"Una investigaci\u00f3n del ISD, presentada en un evento internacional, informa sobre el uso de interfaces cerebro-computadora para el entrenamiento cognitivo en personas con Covid de larga duraci\u00f3n."},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Una estudiante de maestr\u00eda del Programa de Posgrado en Neuroingenier\u00eda (PPGN) del Instituto Santos Dumont (ISD) particip\u00f3 en la Conferencia Internacional IEEE sobre Sistemas Hombre-M\u00e1quina (ICHMS), celebrada en Singapur el 3 de julio, donde present\u00f3 un estudio desarrollado por investigadores del Instituto. La investigaci\u00f3n tiene como objetivo describir el impacto de las interfaces cerebro-computadora en el entrenamiento cognitivo de personas con Covid persistente.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En esa ocasi\u00f3n, la ingeniera biom\u00e9dica y estudiante de m\u00e1ster en ISD, Samara Ten\u00f3rio, present\u00f3 el trabajo &quot;Entrenamiento cognitivo mediante una interfaz cerebro-ordenador para la autorregulaci\u00f3n de la relaci\u00f3n \u03b8\/\u03b2: resultados preliminares con supervivientes de Covid-19 prolongado&quot;, en una participaci\u00f3n virtual en el programa ICHMS, uno de los principales eventos internacionales en el campo de los estudios de interfaces cerebro-ordenador.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El estudio investiga el uso de una interfaz cerebro-computadora asociada con juegos serios (juegos de computadora con prop\u00f3sitos que van m\u00e1s all\u00e1 del mero entretenimiento) como estrategia de rehabilitaci\u00f3n para personas que han desarrollado Covid a largo plazo.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El t\u00e9rmino &quot;Covid persistente&quot; se utiliza para describir el s\u00edndrome cr\u00f3nico que surge tras la recuperaci\u00f3n de un diagn\u00f3stico de Covid-19 y que puede provocar una serie de cambios cognitivos, afectando a las habilidades manuales, la memoria, el razonamiento y la atenci\u00f3n.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La investigaci\u00f3n desarrollada en ISD busca ampliar el conocimiento sobre estas consecuencias mediante una aplicaci\u00f3n interactiva basada en la actividad cerebral. Los resultados, presentados en el evento, refuerzan los hallazgos sobre los cambios en la actividad cerebral asociados con una mayor atenci\u00f3n tras el uso de la tecnolog\u00eda propuesta. Los participantes tambi\u00e9n mostraron mejoras en habilidades cognitivas como la memoria de trabajo y las funciones ejecutivas despu\u00e9s del entrenamiento cognitivo.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cPresentar esta investigaci\u00f3n en un evento internacional de prestigio representa una oportunidad para mostrar el progreso del grupo de investigaci\u00f3n y recibir comentarios de investigadores que trabajan en este campo. Adem\u00e1s, es una forma de acercar la investigaci\u00f3n cient\u00edfica a soluciones con potencial de aplicaci\u00f3n cl\u00ednica y beneficio directo para la sociedad\u201d, afirma Samara Ten\u00f3rio, estudiante de maestr\u00eda del ISD y autora principal del trabajo.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Como muestra de los esfuerzos del ISD por promover la internacionalizaci\u00f3n de la ciencia, la investigaci\u00f3n presentada en el ICHMS se llev\u00f3 a cabo en colaboraci\u00f3n entre el ISD y la Universidad Federal de Esp\u00edrito Santo (UFES) y se integr\u00f3 con socios internacionales como la Universidad de Kumamoto (Jap\u00f3n) y el INRS (Canad\u00e1).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La psic\u00f3loga Jade Carvalho, coautora del estudio, particip\u00f3 en \u00e9l durante su estancia como investigadora visitante en el ISD. Durante este periodo, tuvo acceso a la infraestructura y el equipamiento necesarios para el desarrollo de su investigaci\u00f3n, gracias al programa de Laboratorios Abiertos del Instituto. Para ella, la experiencia en el instituto fue fundamental para su formaci\u00f3n como investigadora.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cEl ISD es un espacio esencial para el desarrollo de la ciencia en Brasil. Mi experiencia en el instituto reforz\u00f3 la idea de que es posible hacer ciencia en el pa\u00eds con un fuerte compromiso con la comunidad. El nivel de apoyo y autonom\u00eda que encontr\u00e9 super\u00f3 mis expectativas\u201d, afirma.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Adem\u00e1s de Samara y Jade, el estudio incluye a los investigadores Yuzen Hatano, Cristian Guerrero-Mendez, Mariane Lima de Souza, Tomohiko Igasaki, Teodiano Bastos-Filho y Tiago H. Falk, as\u00ed como a los profesores de investigaci\u00f3n del ISD Andr\u00e9 Dantas y Denis Delisle Rodriguez (supervisor del estudio).<\/span><\/p>\n<p><b>Acerca del distrito escolar independiente<\/b><\/p>\n<p><span style=\"font-weight: 400;\">El Instituto Santos Dumont (ISD) es una Organizaci\u00f3n Social del Poder Ejecutivo Federal, supervisada por el Ministerio de Educaci\u00f3n, con la intervenci\u00f3n del Ministerio de Deportes. Abarca el Instituto Internacional de Neurociencias Edmond y Lily Safra y el Centro de Educaci\u00f3n e Investigaci\u00f3n en Salud Anita Garibaldi, ambos ubicados en Maca\u00edba. La misi\u00f3n del ISD es promover la educaci\u00f3n para la vida, formando ciudadanos mediante actividades integradas de docencia, investigaci\u00f3n y extensi\u00f3n, adem\u00e1s de contribuir a una transformaci\u00f3n m\u00e1s justa y humana de la realidad social brasile\u00f1a.<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Mestranda do Programa de P\u00f3s-Gradua\u00e7\u00e3o em Neuroengenharia (PPGN) do Instituto Santos Dumont (ISD) participou do evento IEEE International Conference on Human-Machine Systems (ICHMS), realizado em Singapura no dia 3 de julho, com a apresenta\u00e7\u00e3o de um estudo desenvolvido por pesquisadores do Instituto. A pesquisa tem como objetivo descrever os impactos da interface c\u00e9rebro-computador no treinamento [&hellip;]<\/p>","protected":false},"author":20,"featured_media":35557,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,15,10],"tags":[],"class_list":["post-35562","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque_noticia","category-iin-els","category-pesquisa"],"acf":[],"_links":{"self":[{"href":"https:\/\/institutosantosdumont.org.br\/es\/wp-json\/wp\/v2\/posts\/35562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/institutosantosdumont.org.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/institutosantosdumont.org.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/institutosantosdumont.org.br\/es\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/institutosantosdumont.org.br\/es\/wp-json\/wp\/v2\/comments?post=35562"}],"version-history":[{"count":1,"href":"https:\/\/institutosantosdumont.org.br\/es\/wp-json\/wp\/v2\/posts\/35562\/revisions"}],"predecessor-version":[{"id":35563,"href":"https:\/\/institutosantosdumont.org.br\/es\/wp-json\/wp\/v2\/posts\/35562\/revisions\/35563"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/institutosantosdumont.org.br\/es\/wp-json\/wp\/v2\/media\/35557"}],"wp:attachment":[{"href":"https:\/\/institutosantosdumont.org.br\/es\/wp-json\/wp\/v2\/media?parent=35562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/institutosantosdumont.org.br\/es\/wp-json\/wp\/v2\/categories?post=35562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/institutosantosdumont.org.br\/es\/wp-json\/wp\/v2\/tags?post=35562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}